{"id":17697,"date":"2015-08-29T07:03:14","date_gmt":"2015-08-29T05:03:14","guid":{"rendered":"https:\/\/donne4.it\/regioni\/"},"modified":"2026-04-14T16:25:32","modified_gmt":"2026-04-14T14:25:32","slug":"regioni","status":"publish","type":"page","link":"https:\/\/donne4.it\/en\/regioni\/","title":{"rendered":"Regioni"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^4490|url^https:\/\/donne4.it\/wp-content\/uploads\/2021\/09\/fondo-bianco-A4-scaled.jpg|caption^null|alt^null|title^fondo-bianco-A4|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_image_posiiton=&#8221;center top&#8221; enable_overlay=&#8221;enable_overlay_value&#8221; overlay_color=&#8221;rgba(10,10,10,0.5)&#8221; overlay_pattern=&#8221;transperant&#8221; overlay_pattern_opacity=&#8221;80&#8243; overlay_pattern_attachment=&#8221;fixed&#8221; css=&#8221;.vc_custom_1639763693526{margin-bottom: 0px !important;background-color: #ffffff !important;}&#8221; el_class=&#8221;mobile-pad&#8221;][vc_column css=&#8221;.vc_custom_1457638455440{padding-right: 0px !important;padding-left: 0px !important;}&#8221;]<div class=\"ult-spacer spacer-6a050391a9d2c\" data-id=\"6a050391a9d2c\" data-height=\"70\" data-height-mobile=\"30\" data-height-tab=\"50\" data-height-tab-portrait=\"50\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div><div class=\"ult-spacer spacer-6a050391a9da5\" data-id=\"6a050391a9da5\" data-height=\"70\" data-height-mobile=\"30\" data-height-tab=\"50\" data-height-tab-portrait=\"50\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer spacer-6a050391a9df1\" data-id=\"6a050391a9df1\" data-height=\"70\" data-height-mobile=\"30\" data-height-tab=\"50\" data-height-tab-portrait=\"50\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div>[vc_row_inner css=&#8221;.vc_custom_1457638774523{margin: 0px !important;padding: 0px !important;}&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1639765539188{margin-bottom: 10px !important;}&#8221; el_class=&#8221;text-center&#8221;]\n<h1 style=\"color: #eb464a; text-align: center;\">Ambassadors regionali<\/h1>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; style=&#8221;double&#8221; el_width=&#8221;10&#8243; css=&#8221;.vc_custom_1454169758262{margin-top: 0px !important;margin-bottom: 0px !important;}&#8221; accent_color=&#8221;#eb464a&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner]<div class=\"ult-spacer spacer-6a050391a9e34\" data-id=\"6a050391a9e34\" data-height=\"70\" data-height-mobile=\"30\" data-height-tab=\"50\" data-height-tab-portrait=\"50\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-9709\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-9709 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Mancini Loredana<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Cyber Security Consultant<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2021\/09\/FMancini-Loredana.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-5108\"  data-ultimate-target='#info_table_features_wrap-5108.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Lazio<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-2597\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/loredana-mancini-2806b41\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-2597 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-1640\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-1640 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Fontanella Sabrina<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">DEI Trainer &amp; Consultant<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2024\/11\/Profile-Picture_Fontanella.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-7898\"  data-ultimate-target='#info_table_features_wrap-7898.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:14px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:14px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Friuli Venezia Giulia<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-8035\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/sabrina-fontanella\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-8035 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-1234\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-1234 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Tyurenok Victoria<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">BD &amp; Marketing manager<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2025\/11\/Victoria-Tyurenok-photo-e1737045506882-1.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-8546\"  data-ultimate-target='#info_table_features_wrap-8546.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:14px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:14px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Friuli Venezia Giulia<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-6676\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/victoria-tyurenok\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-6676 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-3966\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-3966 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Bruno Giuseppina<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Consulente di Direzione<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2025\/11\/Portrait-Cosenza00074-scaled-e1718722399889-1.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-6072\"  data-ultimate-target='#info_table_features_wrap-6072.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Calabria<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-3772\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/giuseppinabruno-consulting\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-3772 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-3979\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-3979 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Noiosi Stefania<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">HR Consultant<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2021\/09\/FNoiosi-Stefania.jpeg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-6907\"  data-ultimate-target='#info_table_features_wrap-6907.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Piemonte<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-1684\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/stefania-noiosi-75652815a\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-1684 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-9487\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-9487 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Palazzi Patrizia<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Strategic Sales Expert<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2021\/09\/FPalazzi-Patrizia.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-3769\"  data-ultimate-target='#info_table_features_wrap-3769.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Lombardia<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-6531\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/patrizia-palazzi-9a88518\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-6531 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-8565\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-8565 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Zanichelli Gloria<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Digital Trainer<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2021\/09\/FZanichelli-Gloria.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-3636\"  data-ultimate-target='#info_table_features_wrap-3636.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Toscana<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-6530\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/gloriazanichelli\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-6530 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-5059\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-5059 h3'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Capodanno Annamaria<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Responsabile Marketing<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2022\/11\/Capodanno.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-5188\"  data-ultimate-target='#info_table_features_wrap-5188.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Campania<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-8562\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/annamaria-capodanno-5a1250210\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-8562 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-7202\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-7202 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Tagliapietra Elena<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Performative artist<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2024\/03\/1645947709156.jpeg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-7920\"  data-ultimate-target='#info_table_features_wrap-7920.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Veneto<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-6601\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/elenatagliapietra\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-6601 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-1523\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-1523 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Scalone Rosella<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">DE&amp;I Consultant<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2024\/02\/PHOTO-2024-02-19-10-55-22.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-6198\"  data-ultimate-target='#info_table_features_wrap-6198.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Liguria<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-7986\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/rosellascalone\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-7986 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-8656\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-8656 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Gambini Giulia<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Inf. Security Manager<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2025\/11\/DSC_0078-1-scaled-e1731713348997-1.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-8585\"  data-ultimate-target='#info_table_features_wrap-8585.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Marche<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-3037\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/giuliagambini\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-3037 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-4431\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-4431 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Bruno Anna<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">IT Business Manager<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2024\/10\/foto_AB.webp\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-6927\"  data-ultimate-target='#info_table_features_wrap-6927.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Puglia<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-3842\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/anna-bruno-phd-92a91119b\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-3842 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-2930\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-2930 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Pizzi Francesca<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Avvocata civilista<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2024\/02\/1531340865578.jpeg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-3990\"  data-ultimate-target='#info_table_features_wrap-3990.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Emilia Romagna<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-3433\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/francesca-pizzi-95282a6a\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-3433 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-4684\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-4684 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Meloni Neusa<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">CEO<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-01-23-at-09.54.11-e1742044661433.jpeg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-1354\"  data-ultimate-target='#info_table_features_wrap-1354.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Sardegna<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-8703\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/neusa-meloni-68a7b3157\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-8703 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-8926\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-8926 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Del Priore Veronica<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Marketing &amp; Content Manager<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2024\/02\/Veronica-Del-Priore-2.jpg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-9492\"  data-ultimate-target='#info_table_features_wrap-9492.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Umbria<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-2810\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/veronicadelpriore\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-2810 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner css=&#8221;.vc_custom_1457638774523{margin: 0px !important;padding: 0px !important;}&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1709826350125{margin-bottom: 10px !important;}&#8221; el_class=&#8221;text-center&#8221;]\n<h1 style=\"color: #eb464a; text-align: center;\">All&#8217;estero<\/h1>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; style=&#8221;double&#8221; el_width=&#8221;10&#8243; css=&#8221;.vc_custom_1454169758262{margin-top: 0px !important;margin-bottom: 0px !important;}&#8221; accent_color=&#8221;#eb464a&#8221;]<div class=\"ult-spacer spacer-6a050391ae6f5\" data-id=\"6a050391ae6f5\" data-height=\"70\" data-height-mobile=\"30\" data-height-tab=\"50\" data-height-tab-portrait=\"50\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<p style=\"text-align: center;\">Siamo estremamente felici di annunciare che il chapter <strong>Colombia<\/strong> \u00e8 in fase di decollo grazie al lavoro della nostra ambassador Donne 4.0 Rebeca Gomez Tafalla.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;]<div class=\"ult_pricing_table_wrap ult_info_table ult_design_4  ult-cs-custom  \">\r\n\t\t\t\t\t<div class=\"ult_pricing_table info_min_ht\" style=\"background:#fbfbfb;border-top-color:#eb464a; min-height:410px;\"><div id=\"Info-table-wrap-9611\" class=\"ult_pricing_heading\">\r\n\t\t\t\t\t\t\t<h3 class=\"ult-responsive\"  data-ultimate-target='#Info-table-wrap-9611 h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"\"}'  style=\"font-weight:bold;\">Gomez Tafalla Rebeca<\/h3><h5 class=\"ult-responsive\" style=\"font-style:italic;font-weight:normal;\">Imprenditrice<\/h5><\/div><!--ult_pricing_heading--><div class=\"ult_price_body_block\">\r\n\t\t\t\t\t\t\t<div class=\"ult_price_body\">\r\n\t\t\t\t\t\t\t\t<div class=\"ult_price\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon-img \" style=\"font-size:230px;display:inline-block;\" >\n\t<img decoding=\"async\" class=\"img-icon\" alt=\"\" src=\"https:\/\/donne4.it\/wp-content\/uploads\/2022\/10\/Gomez.jpeg\"\/>\n<\/div><\/div><\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/div><!--ult_price_body_block--><div id=\"info_table_features_wrap-9812\"  data-ultimate-target='#info_table_features_wrap-9812.ult_price_features'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  class=\"ult-responsive ult_price_features\" style=\"font-weight:normal;font-size:desktop:16px;px;line-height:desktop:24px;px;\">\r\n\t\t\t\t\t\t\t<p>Ambassador Colombia<\/p>\n\r\n\t\t\t\t\t\t<\/div><!--ult_price_features--><div id=\"info_table_btn_wrap-1260\" class=\"ult_price_link\" style=\"background:#fbfbfb;border-top-color:#eb464a;\">\r\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/rebecagomeztafalla\/\" target=\"_blank\" rel=\"noopener\"   data-ultimate-target='#info_table_btn_wrap-1260 .ult_price_action_button'  data-responsive-json-new='{\"font-size\":\"\",\"line-height\":\"\"}'  class=\"ult-responsive ult_price_action_button\" style=\"background:#eb464a; font-weight:normal;\">LinkedIn<\/a>\r\n\t\t\t\t\t\t<\/div><!--ult_price_link--><div class=\"ult_clr\"><\/div>\r\n\t\t\t<\/div><!--pricing_table-->\r\n\t\t<\/div><!--pricing_table_wrap-->[\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][vc_column width=&#8221;1\/5&#8243;][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"ult-spacer spacer-6a050391aeb3f\" data-id=\"6a050391aeb3f\" data-height=\"60\" data-height-mobile=\"30\" data-height-tab=\"50\" data-height-tab-portrait=\"50\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div>[vc_column_text]\n<p style=\"text-align: center;\">Dopo la visita in Colombia della nostra Presidente Darya Majidi, si \u00e8 consolidata la connessione con l&#8217;Universit\u00e0, le Associazioni femminili di leadership, le aziende e le Istituzioni di Medellin, rendendo possibile la nascita del <strong>Progetto Donne 4.0 Colombia<\/strong>.<\/p>\n[\/vc_column_text]<div class=\"ult-spacer spacer-6a050391aeb93\" data-id=\"6a050391aeb93\" data-height=\"50\" data-height-mobile=\"30\" data-height-tab=\"40\" data-height-tab-portrait=\"40\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div>[vc_gallery type=&#8221;image_grid&#8221; images=&#8221;18138,18141,18108,18120,18129,18132&#8243; img_size=&#8221;medium&#8221;][\/vc_column][\/vc_row][vc_row bg_type=&#8221;bg_color&#8221; el_class=&#8221;mobile-pad&#8221; bg_color_value=&#8221;#ffffff&#8221; css=&#8221;.vc_custom_1457638746280{margin-bottom: 0px !important;}&#8221;][vc_column css=&#8221;.vc_custom_1457638699525{padding-right: 0px !important;padding-left: 0px !important;}&#8221;]<div class=\"ult-spacer spacer-6a050391aebe3\" data-id=\"6a050391aebe3\" data-height=\"70\" data-height-mobile=\"30\" data-height-tab=\"50\" data-height-tab-portrait=\"50\" data-height-mobile-landscape=\"30\" style=\"clear:both;display:block;\"><\/div>[vc_row_inner css=&#8221;.vc_custom_1457638774523{margin: 0px !important;padding: 0px !important;}&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text css=&#8221;.vc_custom_1630865075329{margin-bottom: 10px !important;}&#8221; el_class=&#8221;text-center&#8221;]\n<h1 style=\"color: #eb464a; text-align: center;\">Local partner<\/h1>\n[\/vc_column_text][vc_separator color=&#8221;custom&#8221; style=&#8221;double&#8221; el_width=&#8221;10&#8243; css=&#8221;.vc_custom_1454169758262{margin-top: 0px !important;margin-bottom: 0px !important;}&#8221; accent_color=&#8221;#eb464a&#8221;][vc_column_text css=&#8221;.vc_custom_1631471691288{margin-top: 20px !important;}&#8221; el_class=&#8221;text-center&#8221;]<em>Ecco alcune delle nostre collaborazioni operative. Si tratta di enti pubblici, organizzazioni e imprese che ospitano o facilitano la realizzazione delle nostre attivit\u00e0.<\/em>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][\/vc_row_inner][vc_column_text]\n<div class=\"wpb_text_column wpb_content_element \">\n<div class=\"wpb_wrapper\">\n<p style=\"text-align: center;\"><em><strong>Questa sezione \u00e8 in fase di aggiornamento<\/strong><\/em><\/p>\n<\/div>\n<\/div>\n[\/vc_column_text][vc_row_inner css=&#8221;.vc_custom_1457638799825{margin: 0px !important;padding: 0px !important;}&#8221;][vc_column_inner]<div id=\"ult-carousel-18141634916a050391aed37\" class=\"ult-carousel-wrapper   ult_horizontal\" data-gutter=\"30\" data-rtl=\"false\" ><div class=\"ult-carousel-9754016766a050391aec27 \" >[vc_single_image image=&#8221;16559&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1631471809902{margin-top: 0px !important;margin-right: 0px !important;margin-bottom: 0px !important;margin-left: 0px !important;border-top-width: 0px !important;border-right-width: 0px !important;border-bottom-width: 0px !important;border-left-width: 0px !important;padding-top: 5px !important;padding-right: 5px !important;padding-bottom: 5px !important;padding-left: 5px !important;border-left-color: #dddddd !important;border-left-style: solid !important;border-right-color: #dddddd !important;border-right-style: solid !important;border-top-color: #dddddd !important;border-top-style: solid !important;border-bottom-color: #dddddd !important;border-bottom-style: solid !important;}&#8221;]<\/div><\/div>\t\t\t<script type=\"text\/javascript\">\r\n\t\t\t\tjQuery(document).ready(function ($) {\r\n\t\t\t\t\tif( typeof jQuery('.ult-carousel-9754016766a050391aec27').slick == \"function\"){\r\n\t\t\t\t\t\t$('.ult-carousel-9754016766a050391aec27').slick({dots: false,autoplay: true,autoplaySpeed: 5000,speed: 300,infinite: true,arrows: true,nextArrow: '<button type=\"button\" role=\"button\" aria-label=\"Next\" style=\"color:#eb464a; font-size:20px;\" class=\"slick-next default\"><i class=\"ultsl-arrow-right6\"><\/i><\/button>',prevArrow: '<button type=\"button\" role=\"button\" aria-label=\"Previous\" style=\"color:#eb464a; font-size:20px;\" class=\"slick-prev default\"><i class=\"ultsl-arrow-left6\"><\/i><\/button>',slidesToScroll:1,slidesToShow:4,swipe: true,draggable: true,touchMove: true,pauseOnHover: true,pauseOnFocus: false,responsive: [\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1026,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 4,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1,  \r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 1025,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 3,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t},\r\n\t\t\t\t\t\t\t{\r\n\t\t\t\t\t\t\t  breakpoint: 760,\r\n\t\t\t\t\t\t\t  settings: {\r\n\t\t\t\t\t\t\t\tslidesToShow: 2,\r\n\t\t\t\t\t\t\t\tslidesToScroll: 1\r\n\t\t\t\t\t\t\t  }\r\n\t\t\t\t\t\t\t}\r\n\t\t\t\t\t\t],pauseOnDotsHover: true,customPaging: function(slider, i) {\r\n                   return '<i type=\"button\" style= \"color:#333333;\" class=\"ultsl-record\" data-role=\"none\"><\/i>';\r\n                },});\r\n\t\t\t\t\t}\r\n\t\t\t\t});\r\n\t\t\t<\/script>\r\n\t\t\t[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^4490|url^https:\/\/donne4.it\/wp-content\/uploads\/2021\/09\/fondo-bianco-A4-scaled.jpg|caption^null|alt^null|title^fondo-bianco-A4|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_image_posiiton=&#8221;center top&#8221; enable_overlay=&#8221;enable_overlay_value&#8221; overlay_color=&#8221;rgba(10,10,10,0.5)&#8221; overlay_pattern=&#8221;transperant&#8221; overlay_pattern_opacity=&#8221;80&#8243; overlay_pattern_attachment=&#8221;fixed&#8221; css=&#8221;.vc_custom_1639763693526{margin-bottom: 0px !important;background-color: #ffffff !important;}&#8221; el_class=&#8221;mobile-pad&#8221;][vc_column css=&#8221;.vc_custom_1457638455440{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner css=&#8221;.vc_custom_1457638774523{margin: 0px !important;padding: 0px !important;}&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_column_text [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-homepage.php","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"class_list":["post-17697","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/pages\/17697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/comments?post=17697"}],"version-history":[{"count":12,"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/pages\/17697\/revisions"}],"predecessor-version":[{"id":21109,"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/pages\/17697\/revisions\/21109"}],"wp:attachment":[{"href":"https:\/\/donne4.it\/en\/wp-json\/wp\/v2\/media?parent=17697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}